{"id":44,"date":"2025-10-30T12:23:24","date_gmt":"2025-10-30T11:23:24","guid":{"rendered":"http:\/\/85.215.153.166\/vezere\/?p=44"},"modified":"2026-03-12T10:52:20","modified_gmt":"2026-03-12T09:52:20","slug":"degustation-dhuitres-a-chaillevette-une-experience-100-locale","status":"publish","type":"post","link":"https:\/\/moulindechatressac.com\/es\/degustation-dhuitres-a-chaillevette-une-experience-100-locale\/","title":{"rendered":"Degustaci\u00f3n de ostras en Chaillevette: una experiencia 100 % local"},"content":{"rendered":"\n<div class=\"wp-block-group has-n-brown-color has-text-color has-link-color wp-elements-1 is-layout-constrained wp-container-core-group-is-layout-c12d9882 wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading has-n-brown-color has-text-color has-link-color wp-elements-2\">\u00bfPor qu\u00e9 degustar ostras en Chaillevette?<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong><strong>Ostras de excepci\u00f3n<\/strong><\/strong>\u00a0: Pruebe las <strong>ostras \u201cSp\u00e9ciales de Claire\u201d<\/strong> o las <strong>fines de bouchot<\/strong>, criadas seg\u00fan m\u00e9todos tradicionales.<\/li>\n\n\n\n<li><strong><strong>Un ambiente acogedor<\/strong>e<\/strong>\u00a0: Si\u00e9ntese en las <strong>mesas de madera<\/strong> de las caba\u00f1as ostr\u00edcolas, con los pies en la arena, para una degustaci\u00f3n <strong>frente a las marismas<\/strong>.<\/li>\n\n\n\n<li><strong><strong>Encuentro con los productores<\/strong><\/strong>\u00a0: Los ostricultores estar\u00e1n encantados de explicarle su oficio y de hacerle descubrir sus productos.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00bfD\u00f3nde degustarlas?<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Chez Richard<\/strong> o <strong>Chez Jacky<\/strong>\u00a0: Dos direcciones emblem\u00e1ticas del puerto, donde la acogida es c\u00e1lida y las ostras <strong>ultrafrescas<\/strong>.<\/li>\n\n\n\n<li><strong>El mercado de Chaillevette<\/strong> (en temporada) : Para comprar sus ostras y degustarlas all\u00ed mismo con una copa de <strong>pineau charentais<\/strong>.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Nuestra sugerencia<\/strong>\u00a0: Una <strong>bandeja de ostras<\/strong> acompa\u00f1ada de una <strong>copa de vino blanco seco<\/strong> (un Sauvignon o un Colombard local), con vistas a los <strong>barcos tradicionales<\/strong> y a las <strong>caba\u00f1as de colores<\/strong> de los ostricultores.<\/p>\n\n\n\n<p class=\"has-n-lightest-brown-background-color has-background has-n-outfit-font-family wp-block-paragraph\">\ud83d\udca1\u00a0<strong>Informaci\u00f3n \u00fatil :<\/strong> Recuerde consultar los <strong>horarios de las mareas<\/strong> para disfrutar de la mejor experiencia y lleve <strong>un peque\u00f1o jersey<\/strong>: el viento marino puede ser fresco incluso en verano.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>A pocos minutos a pie del Moulin de Chatressac, el puerto ostr\u00edcola de Chaillevette es una parada imprescindible para los amantes del marisco. Este peque\u00f1o pueblo aut\u00e9ntico, situado en el coraz\u00f3n de las marismas, es conocido por sus ostras de gran calidad, criadas en las ricas aguas del r\u00edo Seudre.<\/p>\n","protected":false},"author":1,"featured_media":442,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-44","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classe"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Degustaci\u00f3n de ostras en Chaillevette: una experiencia 100 % local<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/moulindechatressac.com\/es\/degustation-dhuitres-a-chaillevette-une-experience-100-locale\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:locale:alternate\" content=\"en_UK\" \/>\n<meta property=\"og:locale:alternate\" content=\"fr_FR\" \/>\n<meta property=\"og:locale:alternate\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Degustaci\u00f3n de ostras en Chaillevette: una experiencia 100 % local\" \/>\n<meta property=\"og:description\" content=\"A pocos minutos a pie del Moulin de Chatressac, el puerto ostr\u00edcola de Chaillevette es una parada imprescindible para los amantes del marisco. Este peque\u00f1o pueblo aut\u00e9ntico, situado en el coraz\u00f3n de las marismas, es conocido por sus ostras de gran calidad, criadas en las ricas aguas del r\u00edo Seudre.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/moulindechatressac.com\/es\/degustation-dhuitres-a-chaillevette-une-experience-100-locale\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Moulin de Chatressac\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-30T11:23:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-12T09:52:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/moulindechatressac.com\/wp-content\/uploads\/2025\/10\/mitili-mitili-huitres.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"665\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/moulindechatressac.com\\\/es\\\/degustation-dhuitres-a-chaillevette-une-experience-100-locale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/moulindechatressac.com\\\/es\\\/degustation-dhuitres-a-chaillevette-une-experience-100-locale\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/moulindechatressac.com\\\/#\\\/schema\\\/person\\\/01df641aff43c49faa941ca61a0b1514\"},\"headline\":\"Degustaci\u00f3n de ostras en Chaillevette: una experiencia 100 % local\",\"datePublished\":\"2025-10-30T11:23:24+00:00\",\"dateModified\":\"2026-03-12T09:52:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/moulindechatressac.com\\\/es\\\/degustation-dhuitres-a-chaillevette-une-experience-100-locale\\\/\"},\"wordCount\":580,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/moulindechatressac.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/moulindechatressac.com\\\/es\\\/degustation-dhuitres-a-chaillevette-une-experience-100-locale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/moulindechatressac.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/mitili-mitili-huitres.jpg\",\"articleSection\":[\"Non class\u00e9\"],\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/moulindechatressac.com\\\/es\\\/degustation-dhuitres-a-chaillevette-une-experience-100-locale\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/moulindechatressac.com\\\/es\\\/degustation-dhuitres-a-chaillevette-une-experience-100-locale\\\/\",\"url\":\"https:\\\/\\\/moulindechatressac.com\\\/es\\\/degustation-dhuitres-a-chaillevette-une-experience-100-locale\\\/\",\"name\":\"Degustaci\u00f3n de ostras en Chaillevette: una experiencia 100 % local\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/moulindechatressac.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/moulindechatressac.com\\\/es\\\/degustation-dhuitres-a-chaillevette-une-experience-100-locale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/moulindechatressac.com\\\/es\\\/degustation-dhuitres-a-chaillevette-une-experience-100-locale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/moulindechatressac.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/mitili-mitili-huitres.jpg\",\"datePublished\":\"2025-10-30T11:23:24+00:00\",\"dateModified\":\"2026-03-12T09:52:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/moulindechatressac.com\\\/es\\\/degustation-dhuitres-a-chaillevette-une-experience-100-locale\\\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/moulindechatressac.com\\\/es\\\/degustation-dhuitres-a-chaillevette-une-experience-100-locale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/moulindechatressac.com\\\/es\\\/degustation-dhuitres-a-chaillevette-une-experience-100-locale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/moulindechatressac.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/mitili-mitili-huitres.jpg\",\"contentUrl\":\"https:\\\/\\\/moulindechatressac.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/mitili-mitili-huitres.jpg\",\"width\":665,\"height\":1000,\"caption\":\"Photo de Mitili Mitili sur Unsplash\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/moulindechatressac.com\\\/es\\\/degustation-dhuitres-a-chaillevette-une-experience-100-locale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/moulindechatressac.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Degustaci\u00f3n de ostras en Chaillevette: una experiencia 100 % local\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/moulindechatressac.com\\\/#website\",\"url\":\"https:\\\/\\\/moulindechatressac.com\\\/\",\"name\":\"Le Moulin de Chatressac\",\"description\":\"Alojamientos con encanto en un antiguo molino en Charente-Maritime\",\"publisher\":{\"@id\":\"https:\\\/\\\/moulindechatressac.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/moulindechatressac.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/moulindechatressac.com\\\/#organization\",\"name\":\"Le Moulin de Chatressac\",\"url\":\"https:\\\/\\\/moulindechatressac.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/moulindechatressac.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/moulindechatressac.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/logo-moulin-chatressac.png\",\"contentUrl\":\"https:\\\/\\\/moulindechatressac.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/logo-moulin-chatressac.png\",\"width\":546,\"height\":125,\"caption\":\"Le Moulin de Chatressac\"},\"image\":{\"@id\":\"https:\\\/\\\/moulindechatressac.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/moulindechatressac.com\\\/#\\\/schema\\\/person\\\/01df641aff43c49faa941ca61a0b1514\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b9f6d9e73c940b8cc7a1b62be9b202567721e3207327311ad875b64dd330ce23?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b9f6d9e73c940b8cc7a1b62be9b202567721e3207327311ad875b64dd330ce23?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b9f6d9e73c940b8cc7a1b62be9b202567721e3207327311ad875b64dd330ce23?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"http:\\\/\\\/85.215.153.166\\\/vezere\"],\"url\":\"https:\\\/\\\/moulindechatressac.com\\\/es\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Degustaci\u00f3n de ostras en Chaillevette: una experiencia 100 % local","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/moulindechatressac.com\/es\/degustation-dhuitres-a-chaillevette-une-experience-100-locale\/","og_locale":"es_ES","og_type":"article","og_title":"[:en]Oyster Tasting in Chaillevette: A 100% Local Experience[:fr]D\u00e9gustation d\u2019hu\u00eetres \u00e0 Chaillevette : Une exp\u00e9rience 100 % locale[:es]Degustaci\u00f3n de ostras en Chaillevette: una experiencia 100 % local[:] - Le Moulin de Chatressac","og_description":"A pocos minutos a pie del Moulin de Chatressac, el puerto ostr\u00edcola de Chaillevette es una parada imprescindible para los amantes del marisco. Este peque\u00f1o pueblo aut\u00e9ntico, situado en el coraz\u00f3n de las marismas, es conocido por sus ostras de gran calidad, criadas en las ricas aguas del r\u00edo Seudre.","og_url":"https:\/\/moulindechatressac.com\/es\/degustation-dhuitres-a-chaillevette-une-experience-100-locale\/","og_site_name":"Le Moulin de Chatressac","article_published_time":"2025-10-30T11:23:24+00:00","article_modified_time":"2026-03-12T09:52:20+00:00","og_image":[{"width":665,"height":1000,"url":"https:\/\/moulindechatressac.com\/wp-content\/uploads\/2025\/10\/mitili-mitili-huitres.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/moulindechatressac.com\/es\/degustation-dhuitres-a-chaillevette-une-experience-100-locale\/#article","isPartOf":{"@id":"https:\/\/moulindechatressac.com\/es\/degustation-dhuitres-a-chaillevette-une-experience-100-locale\/"},"author":{"name":"admin","@id":"https:\/\/moulindechatressac.com\/#\/schema\/person\/01df641aff43c49faa941ca61a0b1514"},"headline":"Degustaci\u00f3n de ostras en Chaillevette: una experiencia 100 % local","datePublished":"2025-10-30T11:23:24+00:00","dateModified":"2026-03-12T09:52:20+00:00","mainEntityOfPage":{"@id":"https:\/\/moulindechatressac.com\/es\/degustation-dhuitres-a-chaillevette-une-experience-100-locale\/"},"wordCount":580,"commentCount":0,"publisher":{"@id":"https:\/\/moulindechatressac.com\/#organization"},"image":{"@id":"https:\/\/moulindechatressac.com\/es\/degustation-dhuitres-a-chaillevette-une-experience-100-locale\/#primaryimage"},"thumbnailUrl":"https:\/\/moulindechatressac.com\/wp-content\/uploads\/2025\/10\/mitili-mitili-huitres.jpg","articleSection":["Non class\u00e9"],"inLanguage":"es-ES","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/moulindechatressac.com\/es\/degustation-dhuitres-a-chaillevette-une-experience-100-locale\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/moulindechatressac.com\/es\/degustation-dhuitres-a-chaillevette-une-experience-100-locale\/","url":"https:\/\/moulindechatressac.com\/es\/degustation-dhuitres-a-chaillevette-une-experience-100-locale\/","name":"Degustaci\u00f3n de ostras en Chaillevette: una experiencia 100 % local","isPartOf":{"@id":"https:\/\/moulindechatressac.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/moulindechatressac.com\/es\/degustation-dhuitres-a-chaillevette-une-experience-100-locale\/#primaryimage"},"image":{"@id":"https:\/\/moulindechatressac.com\/es\/degustation-dhuitres-a-chaillevette-une-experience-100-locale\/#primaryimage"},"thumbnailUrl":"https:\/\/moulindechatressac.com\/wp-content\/uploads\/2025\/10\/mitili-mitili-huitres.jpg","datePublished":"2025-10-30T11:23:24+00:00","dateModified":"2026-03-12T09:52:20+00:00","breadcrumb":{"@id":"https:\/\/moulindechatressac.com\/es\/degustation-dhuitres-a-chaillevette-une-experience-100-locale\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/moulindechatressac.com\/es\/degustation-dhuitres-a-chaillevette-une-experience-100-locale\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/moulindechatressac.com\/es\/degustation-dhuitres-a-chaillevette-une-experience-100-locale\/#primaryimage","url":"https:\/\/moulindechatressac.com\/wp-content\/uploads\/2025\/10\/mitili-mitili-huitres.jpg","contentUrl":"https:\/\/moulindechatressac.com\/wp-content\/uploads\/2025\/10\/mitili-mitili-huitres.jpg","width":665,"height":1000,"caption":"Photo de Mitili Mitili sur Unsplash"},{"@type":"BreadcrumbList","@id":"https:\/\/moulindechatressac.com\/es\/degustation-dhuitres-a-chaillevette-une-experience-100-locale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/moulindechatressac.com\/es\/"},{"@type":"ListItem","position":2,"name":"Degustaci\u00f3n de ostras en Chaillevette: una experiencia 100 % local"}]},{"@type":"WebSite","@id":"https:\/\/moulindechatressac.com\/#website","url":"https:\/\/moulindechatressac.com\/","name":"Le Moulin de Chatressac","description":"Alojamientos con encanto en un antiguo molino en Charente-Maritime","publisher":{"@id":"https:\/\/moulindechatressac.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/moulindechatressac.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/moulindechatressac.com\/#organization","name":"Le Moulin de Chatressac","url":"https:\/\/moulindechatressac.com\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/moulindechatressac.com\/#\/schema\/logo\/image\/","url":"https:\/\/moulindechatressac.com\/wp-content\/uploads\/2026\/02\/logo-moulin-chatressac.png","contentUrl":"https:\/\/moulindechatressac.com\/wp-content\/uploads\/2026\/02\/logo-moulin-chatressac.png","width":546,"height":125,"caption":"Le Moulin de Chatressac"},"image":{"@id":"https:\/\/moulindechatressac.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/moulindechatressac.com\/#\/schema\/person\/01df641aff43c49faa941ca61a0b1514","name":"admin","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/b9f6d9e73c940b8cc7a1b62be9b202567721e3207327311ad875b64dd330ce23?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b9f6d9e73c940b8cc7a1b62be9b202567721e3207327311ad875b64dd330ce23?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b9f6d9e73c940b8cc7a1b62be9b202567721e3207327311ad875b64dd330ce23?s=96&d=mm&r=g","caption":"admin"},"sameAs":["http:\/\/85.215.153.166\/vezere"],"url":"https:\/\/moulindechatressac.com\/es\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/moulindechatressac.com\/es\/wp-json\/wp\/v2\/posts\/44","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/moulindechatressac.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/moulindechatressac.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/moulindechatressac.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/moulindechatressac.com\/es\/wp-json\/wp\/v2\/comments?post=44"}],"version-history":[{"count":7,"href":"https:\/\/moulindechatressac.com\/es\/wp-json\/wp\/v2\/posts\/44\/revisions"}],"predecessor-version":[{"id":848,"href":"https:\/\/moulindechatressac.com\/es\/wp-json\/wp\/v2\/posts\/44\/revisions\/848"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/moulindechatressac.com\/es\/wp-json\/wp\/v2\/media\/442"}],"wp:attachment":[{"href":"https:\/\/moulindechatressac.com\/es\/wp-json\/wp\/v2\/media?parent=44"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/moulindechatressac.com\/es\/wp-json\/wp\/v2\/categories?post=44"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/moulindechatressac.com\/es\/wp-json\/wp\/v2\/tags?post=44"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}